{"id":3709,"date":"2023-10-05T15:31:10","date_gmt":"2023-10-05T15:31:10","guid":{"rendered":"https:\/\/tenisdemesaacre.com.br\/site\/?p=3709"},"modified":"2023-10-05T15:31:30","modified_gmt":"2023-10-05T15:31:30","slug":"inscricoes-para-a-quinta-etapa-tmb-estadual-do-circuito-acreano-de-tenis-de-mesa-de-2023","status":"publish","type":"post","link":"https:\/\/tenisdemesaacre.com.br\/site\/inscricoes-para-a-quinta-etapa-tmb-estadual-do-circuito-acreano-de-tenis-de-mesa-de-2023\/","title":{"rendered":"Inscri\u00e7\u00f5es para a Quinta Etapa Tmb Estadual do circuito acreano de t\u00eanis de mesa de 2023"},"content":{"rendered":"\n<p>Informamos que foi criado o evento 3815, Quinta Etapa Tmb Estadual do circuito acreano de t\u00eanis de mesa de 2023, no Sistema CBTM web.<br>As inscri\u00e7\u00f5es iniciam hoje 02\/10\/2023 e termina no dia 17\/10\/2023.<br>Os clubes para os atletas se inscreverem s\u00e3o:<br>Aabb Acre .<br><\/p>\n\n\n\n<p>Id : aabbac &#8211; senha 123<br><\/p>\n\n\n\n<p>Aatm :<br>Id : associacao30 &#8211; senha 123<br><\/p>\n\n\n\n<p>O calend\u00e1rio para o Tmb Estadual Quinta Etapa obedecem as seguintes datas:<br>Dia 20\/10 (sexta-feira) Absoluto D masculino<br>Dia 24\/10(ter\u00e7a feira) Veteranos 40+, e Absoluto D Feminino<br>Dia 27\/10 (sexta-feira) Rating B masculino, infantil Feminino e Infantil Masculino .<br><\/p>\n\n\n\n<p>Para os atletas que jogam o Rating B masculino os atletas devem marcar o quadradinho azul participa do Rating(quem joga o Rating B masculino por obrigatoriedade devem marcar o quadradinho azul participa do Rating) se for participar em outras categorias al\u00e9m do Rating \u00e9 s\u00f3 marcar o que o Sistema disponibiliza dentro dos crit\u00e9rios de participa\u00e7\u00e3o das categorias normatizados pela FTMEAC.<br><\/p>\n\n\n\n<p>Segue o link para as inscri\u00e7\u00f5es:<br><a href=\"https:\/\/app.cbtm.org.br\/UI\/Login\/Login\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/app.cbtm.org.br\/UI\/Login\/Login<\/a><br><\/p>\n\n\n\n<p>Lembrando a todos os atletas que ainda n\u00e3o pagaram a TRA devem fazer o pagamento at\u00e9 o dia 13\/10\/2023 para que possam participar da terceira etapa..Membro Ouro o valor est\u00e1 R$170,00 e o membro prata o valor de R$140,00<\/p>\n\n\n\n<p><br>Caso n\u00e3o estejam conseguindo gerar o boleto para o pagamento da TRA \u00e9 s\u00f3 falar comigo no privado que gero o boleto e envio para os que est\u00e3o tendo dificuldades em gerar os boletos.<\/p>\n\n\n\n<p><br>Qualquer d\u00favida ou esclarecimentos estamos ao dispor.<\/p>\n\n\n\n<p><br>Atte<\/p>\n\n\n\n<p><br>Manoel Bento Sobrinho<br>Dirigente da FTMEAC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informamos que foi criado o evento 3815, Quinta Etapa Tmb Estadual do circuito acreano de t\u00eanis de mesa de 2023, no Sistema CBTM web.As inscri\u00e7\u00f5es iniciam hoje 02\/10\/2023 e termina no dia 17\/10\/2023.Os clubes para os atletas se inscreverem s\u00e3o:Aabb Acre . Id : aabbac &#8211; senha 123 Aatm :Id : associacao30 &#8211; senha 123 [&hellip;]<\/p>\n","protected":false},"author":21624,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3709","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/posts\/3709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/users\/21624"}],"replies":[{"embeddable":true,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/comments?post=3709"}],"version-history":[{"count":2,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/posts\/3709\/revisions"}],"predecessor-version":[{"id":3711,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/posts\/3709\/revisions\/3711"}],"wp:attachment":[{"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/media?parent=3709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/categories?post=3709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/tags?post=3709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}