{"id":4175,"date":"2025-04-29T19:34:11","date_gmt":"2025-04-29T19:34:11","guid":{"rendered":"https:\/\/tenisdemesaacre.com.br\/site\/?p=4175"},"modified":"2025-05-11T19:43:24","modified_gmt":"2025-05-11T19:43:24","slug":"segunda-etapa-tmb-estadual-acre-2025-3","status":"publish","type":"post","link":"https:\/\/tenisdemesaacre.com.br\/site\/segunda-etapa-tmb-estadual-acre-2025-3\/","title":{"rendered":"SEGUNDA ETAPA \u2013 TMB ESTADUAL ACRE 2025"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">CATEGORIAS: ABSOLUTO D MASCULINO, INFANTIL MASCULINO E FEMININO, MIRIM MASCULINO<\/h5>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.57-edited-scaled.jpeg\" alt=\"\" class=\"wp-image-4177\" srcset=\"https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.57-edited-scaled.jpeg 2560w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.57-edited-300x200.jpeg 300w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.57-edited-1024x683.jpeg 1024w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.57-edited-768x512.jpeg 768w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.57-edited-1536x1024.jpeg 1536w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.57-edited-2048x1366.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<p>A <strong>Segunda Etapa do TMB Estadual Acre 2025<\/strong> foi realizada no dia <strong>29 de abril de 2025<\/strong>, no <strong>Gin\u00e1sio da AABB Rio Branco<\/strong>, com a participa\u00e7\u00e3o de atletas das categorias de base e adulto, demonstrando grande esp\u00edrito esportivo e excelentes disputas. Confira os resultados:<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Categoria: Infantil Feminino<\/strong><\/h5>\n\n\n\n<p><strong>Data:<\/strong> 29\/04\/2025<br><strong>Hor\u00e1rio:<\/strong> 19h30 \u00e0s 20h00<\/p>\n\n\n\n<p><strong>Forma de disputa:<\/strong> um grupo com duas atletas jogando entre si.<br><strong>Classifica\u00e7\u00e3o final:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Atleta<\/th><th>Classifica\u00e7\u00e3o<\/th><th>Pontua\u00e7\u00e3o FTMEAC<\/th><th>Pontua\u00e7\u00e3o CBTM<\/th><\/tr><\/thead><tbody><tr><td>Luiza Souza Assis<\/td><td>1\u00ba lugar<\/td><td>500<\/td><td>400<\/td><\/tr><tr><td>Luiza Holanda<\/td><td>2\u00ba lugar<\/td><td>400<\/td><td>280<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.28.06-edited-scaled.jpeg\" alt=\"\" class=\"wp-image-4179\" srcset=\"https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.28.06-edited-scaled.jpeg 1920w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.28.06-edited-225x300.jpeg 225w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.28.06-edited-768x1024.jpeg 768w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.28.06-edited-1152x1536.jpeg 1152w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.28.06-edited-1536x2048.jpeg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Categoria: Infantil Masculino<\/strong><\/h3>\n\n\n\n<p><strong>Data:<\/strong> 29\/04\/2025<br><strong>Hor\u00e1rio:<\/strong> 20h30 \u00e0s 21h30<\/p>\n\n\n\n<p><strong>Forma de disputa:<\/strong> um grupo com quatro atletas, jogando todos contra todos.<br><strong>Total de partidas:<\/strong> 6<br><strong>Classifica\u00e7\u00e3o final:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Atleta<\/th><th>Classifica\u00e7\u00e3o<\/th><th>Pontua\u00e7\u00e3o FTMEAC<\/th><th>Pontua\u00e7\u00e3o CBTM<\/th><\/tr><\/thead><tbody><tr><td>Caik Moreira<\/td><td>1\u00ba lugar<\/td><td>500<\/td><td>400<\/td><\/tr><tr><td>Ruan Gabriel<\/td><td>2\u00ba lugar<\/td><td>400<\/td><td>280<\/td><\/tr><tr><td>Andrey A. Lebre<\/td><td>3\u00ba lugar<\/td><td>250<\/td><td>140<\/td><\/tr><tr><td>Jo\u00e3o Silva<\/td><td>3\u00ba lugar<\/td><td>250<\/td><td>140<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.55-edited-scaled.jpeg\" alt=\"\" class=\"wp-image-4182\" srcset=\"https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.55-edited-scaled.jpeg 2560w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.55-edited-300x300.jpeg 300w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.55-edited-1024x1024.jpeg 1024w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.55-edited-150x150.jpeg 150w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.55-edited-768x768.jpeg 768w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.55-edited-1536x1536.jpeg 1536w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.55-edited-2048x2048.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Categoria: Mirim Masculino<\/strong><\/h3>\n\n\n\n<p><strong>Data:<\/strong> 29\/04\/2025<br><strong>Hor\u00e1rio:<\/strong> 19h30 \u00e0s 20h30<\/p>\n\n\n\n<p><strong>Forma de disputa:<\/strong> um grupo com tr\u00eas atletas, jogando todos contra todos.<br><strong>Total de partidas:<\/strong> 3<br><strong>Classifica\u00e7\u00e3o final:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Atleta<\/th><th>Classifica\u00e7\u00e3o<\/th><th>Pontua\u00e7\u00e3o FTMEAC<\/th><th>Pontua\u00e7\u00e3o CBTM<\/th><\/tr><\/thead><tbody><tr><td>Andrey Lebre<\/td><td>1\u00ba lugar<\/td><td>500<\/td><td>400<\/td><\/tr><tr><td>Felipe Rodrigues<\/td><td>2\u00ba lugar<\/td><td>400<\/td><td>280<\/td><\/tr><tr><td>Luiz Paulo Costa<\/td><td>3\u00ba lugar<\/td><td>250<\/td><td>140<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"1024\" src=\"https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.56-771x1024.jpeg\" alt=\"\" class=\"wp-image-4180\" srcset=\"https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.56-771x1024.jpeg 771w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.56-226x300.jpeg 226w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.56-768x1020.jpeg 768w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.56-1157x1536.jpeg 1157w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.56-1542x2048.jpeg 1542w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-14.27.56-scaled.jpeg 1928w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Categoria: Absoluto D Masculino<\/strong><\/h3>\n\n\n\n<p><strong>Data:<\/strong> 29\/04\/2025<br><strong>Hor\u00e1rio:<\/strong> 19h45 \u00e0s 23h00<\/p>\n\n\n\n<p><strong>Forma de disputa:<\/strong> dois grupos com tr\u00eas atletas e dois grupos com quatro atletas, jogando entre si. Classificaram-se os dois melhores de cada grupo para as fases eliminat\u00f3rias.<br><strong>Total de partidas:<\/strong> 25<br><strong>Classifica\u00e7\u00e3o final:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Atleta<\/th><th>Classifica\u00e7\u00e3o<\/th><th>Pontua\u00e7\u00e3o FTMEAC<\/th><th>Pontua\u00e7\u00e3o CBTM<\/th><\/tr><\/thead><tbody><tr><td>Ian Felipe Oliveira<\/td><td>1\u00ba lugar<\/td><td>500<\/td><td>400<\/td><\/tr><tr><td>Luis Montelano<\/td><td>2\u00ba lugar<\/td><td>400<\/td><td>280<\/td><\/tr><tr><td>Wennedy Filgueira<\/td><td>3\u00ba lugar<\/td><td>250<\/td><td>140<\/td><\/tr><tr><td>Guaracy Duarte<\/td><td>3\u00ba lugar<\/td><td>250<\/td><td>140<\/td><\/tr><tr><td>Izandro Brito<\/td><td>5\u00ba lugar<\/td><td>180<\/td><td>70<\/td><\/tr><tr><td>Nilton Sandro<\/td><td>6\u00ba lugar<\/td><td>160<\/td><td>70<\/td><\/tr><tr><td>El\u00e1sio Oliveira<\/td><td>7\u00ba lugar<\/td><td>140<\/td><td>70<\/td><\/tr><tr><td>Neyvo Souza<\/td><td>8\u00ba lugar<\/td><td>120<\/td><td>70<\/td><\/tr><tr><td>Moacir Neto<\/td><td>9\u00ba lugar<\/td><td>100<\/td><td>4<\/td><\/tr><tr><td>Gustavo Rodrigues<\/td><td>10\u00ba lugar<\/td><td>80<\/td><td>4<\/td><\/tr><tr><td>Evairton Nascimento<\/td><td>11\u00ba lugar<\/td><td>60<\/td><td>4<\/td><\/tr><tr><td>Gleysson Maia<\/td><td>12\u00ba lugar<\/td><td>50<\/td><td>4<\/td><\/tr><tr><td>Josemir Rebou\u00e7as<\/td><td>13\u00ba lugar<\/td><td>40<\/td><td>4<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Observa\u00e7\u00e3o:<\/strong> o atleta <strong>Ant\u00f4nio Concei\u00e7\u00e3o Santos<\/strong> n\u00e3o compareceu ao evento, sendo considerado <strong>W.O.<\/strong> em suas respectivas partidas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-15.10.55-edited.jpeg\" alt=\"\" class=\"wp-image-4184\" srcset=\"https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-15.10.55-edited.jpeg 1200w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-15.10.55-edited-300x300.jpeg 300w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-15.10.55-edited-1024x1024.jpeg 1024w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-15.10.55-edited-150x150.jpeg 150w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-30-at-15.10.55-edited-768x768.jpeg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p>A <strong>FTMEAC<\/strong> agradece a todos os atletas das categorias <em>Absoluto D Masculino, Infantil Masculino e Feminino, e Mirim Masculino<\/em> pela garra, esfor\u00e7o e determina\u00e7\u00e3o demonstrados durante a <strong>Segunda Etapa do TMB Estadual Acre 2025<\/strong>.<\/p>\n\n\n\n<p>Esperamos contar com a presen\u00e7a de todos na <strong>Terceira Etapa<\/strong>, que ser\u00e1 realizada entre os dias <strong>13 e 20 de junho de 2025<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATEGORIAS: ABSOLUTO D MASCULINO, INFANTIL MASCULINO E FEMININO, MIRIM MASCULINO A Segunda Etapa do TMB Estadual Acre 2025 foi realizada no dia 29 de abril de 2025, no Gin\u00e1sio da AABB Rio Branco, com a participa\u00e7\u00e3o de atletas das categorias de base e adulto, demonstrando grande esp\u00edrito esportivo e excelentes disputas. Confira os resultados: Categoria: [&hellip;]<\/p>\n","protected":false},"author":21624,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4175","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/posts\/4175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/users\/21624"}],"replies":[{"embeddable":true,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/comments?post=4175"}],"version-history":[{"count":1,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/posts\/4175\/revisions"}],"predecessor-version":[{"id":4185,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/posts\/4175\/revisions\/4185"}],"wp:attachment":[{"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/media?parent=4175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/categories?post=4175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/tags?post=4175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}