{"id":4263,"date":"2025-08-14T04:17:02","date_gmt":"2025-08-14T04:17:02","guid":{"rendered":"https:\/\/tenisdemesaacre.com.br\/site\/?p=4263"},"modified":"2025-08-14T04:17:03","modified_gmt":"2025-08-14T04:17:03","slug":"definidos-campeoes-do-tenis-de-mesa-na-fase-estadual-dos-jogos-estudantis-do-acre","status":"publish","type":"post","link":"https:\/\/tenisdemesaacre.com.br\/site\/definidos-campeoes-do-tenis-de-mesa-na-fase-estadual-dos-jogos-estudantis-do-acre\/","title":{"rendered":"Definidos campe\u00f5es do t\u00eanis de mesa na fase estadual dos Jogos Estudantis do Acre"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-09-at-20.32.47-1-1024x576.jpeg\" alt=\"\" class=\"wp-image-4264\" srcset=\"https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-09-at-20.32.47-1-1024x576.jpeg 1024w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-09-at-20.32.47-1-300x169.jpeg 300w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-09-at-20.32.47-1-768x432.jpeg 768w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-09-at-20.32.47-1-1536x864.jpeg 1536w, https:\/\/tenisdemesaacre.com.br\/site\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-09-at-20.32.47-1-2048x1152.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Fases municipal e estadual das categorias 12 a 14 anos e 14 a a 15 anos em ambos naipes foram disputadas nesse s\u00e1bado, na AABB, em Rio Branco. Campe\u00f5es e vices v\u00e3o \u00e0 fase nacional<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Os mesatenistas que v\u00e3o representar o Acre na fase nacional dos Jogos Estudantis est\u00e3o definidos<\/strong>. A classificat\u00f3ria do t\u00eanis de mesa com atletas at\u00e9 15 anos em ambos os naipes foi disputada nesse s\u00e1bado (9), na Associa\u00e7\u00e3o Atl\u00e9tica Banco do Brasil (AABB), em Rio Branco.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Veja a mat\u00e9ria completa em: <a href=\"https:\/\/ge.globo.com\/ac\/noticia\/2025\/08\/11\/definidos-campeoes-do-tenis-de-mesa-na-fase-estadual-dos-jogos-estudantis-do-acre.ghtml?utm_source=whatsapp&amp;utm_medium=share-bar-mobile&amp;utm_campaign=materias\">https:\/\/ge.globo.com\/ac\/noticia\/2025\/08\/11\/definidos-campeoes-do-tenis-de-mesa-na-fase-estadual-dos-jogos-estudantis-do-acre.ghtml?utm_source=whatsapp&amp;utm_medium=share-bar-mobile&amp;utm_campaign=materias<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fases municipal e estadual das categorias 12 a 14 anos e 14 a a 15 anos em ambos naipes foram disputadas nesse s\u00e1bado, na AABB, em Rio Branco. Campe\u00f5es e vices v\u00e3o \u00e0 fase nacional Os mesatenistas que v\u00e3o representar o Acre na fase nacional dos Jogos Estudantis est\u00e3o definidos. A classificat\u00f3ria do t\u00eanis de [&hellip;]<\/p>\n","protected":false},"author":21624,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4263","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/posts\/4263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/users\/21624"}],"replies":[{"embeddable":true,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/comments?post=4263"}],"version-history":[{"count":1,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/posts\/4263\/revisions"}],"predecessor-version":[{"id":4265,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/posts\/4263\/revisions\/4265"}],"wp:attachment":[{"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/media?parent=4263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/categories?post=4263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tenisdemesaacre.com.br\/site\/wp-json\/wp\/v2\/tags?post=4263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}